{"id":71735,"date":"2023-03-09T10:40:42","date_gmt":"2023-03-09T09:40:42","guid":{"rendered":"https:\/\/www.aurigaspa.com\/?p=71735"},"modified":"2023-05-10T11:26:18","modified_gmt":"2023-05-10T10:26:18","slug":"auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos","status":"publish","type":"post","link":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/","title":{"rendered":"Auriga y CMS en Ecuador para los proyectos de transformaci\u00f3n de los cajeros autom\u00e1ticos"},"content":{"rendered":"<p>A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia de banca omnicanal con acceso 24\/7 a servicios personalizados, contextualizados en tiempo real, con lo que ayuda a las instituciones financieras ecuatorianas a ofrecer una mayor eficiencia operativa.<\/p>\n<p>Aqu\u00ed una recopilaci\u00f3n de los art\u00edculos m\u00e1s interesantes sobre la alianza entre Auriga y CMS.<\/p>\n<div class=\"table-responsive\">\n<table class=\"table table-striped liste_particolari\">\n<tbody>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"http:\/\/www.businessempresarial.com.pe\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">09\/03\/2023<\/p>\n<p class=\"title\">Business Empresarial<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/globalbuenosaires.com.ar\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">09\/03\/2023<\/p>\n<p class=\"title\">Global Buenos Aires<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/www.technopatas.com\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">09\/03\/2023<\/p>\n<p class=\"title\">Technopatas<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/www.evisos.com.pe\/noticias\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos-en-ecuador-business-empresarial\/\">\n<td>\n<p class=\"date\">09\/03\/2023<\/p>\n<p class=\"title\">eNoticias Per\u00fa<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador \u2013 Business Empresarial<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/www.tecnogus.com.co\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">06\/03\/2023<\/p>\n<p class=\"title\">Tecnogus<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/www.america-retail.com\/omnicanalidad\/transformacion-digital-de-los-cajeros-automaticos\/\">\n<td>\n<p class=\"date\">06\/03\/2023<\/p>\n<p class=\"title\">Am\u00e9rica Retail<\/p>\n<p class=\"sub\">Transformaci\u00f3n digital de los cajeros autom\u00e1ticos<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"http:\/\/www.periodista.com.ar\/notas0323\/06032023ah.htm\">\n<td>\n<p class=\"date\">06\/03\/2023<\/p>\n<p class=\"title\">HyperData<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/tynmagazine.com\/transformacion-digital-de-los-cajeros-automaticos\/\">\n<td>\n<p class=\"date\">03\/03\/2023<\/p>\n<p class=\"title\">TyN Magazine<\/p>\n<p class=\"sub\">Transformaci\u00f3n digital de los cajeros autom\u00e1ticos<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/elpostalweb.mx\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos\/\">\n<td>\n<p class=\"date\">02\/03\/2023<\/p>\n<p class=\"title\">El Postal Web<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/www.america-retail.com\/omnicanalidad\/auriga-y-cms-apoyan-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">02\/03\/2023<\/p>\n<p class=\"title\">America Retail<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"http:\/\/www.emb.cl\/gerencia\/noticia.mvc?nid=20230302p1&amp;ni=auriga-y-cms-apoyan-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\">\n<td>\n<p class=\"date\">02\/03\/2023<\/p>\n<p class=\"title\">Revista Gerencia<\/p>\n<p class=\"sub\">Auriga y CMS apoyan transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/itusers.today\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">02\/03\/2023<\/p>\n<p class=\"title\">IT Users<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/www.miambiente.com.mx\/notas\/auriga-y-cms-apoyan-transformacion-digital-de-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">01\/03\/2023<\/p>\n<p class=\"title\">Mi Ambiente<\/p>\n<p class=\"sub\">Auriga y CMS apoyan transformaci\u00f3n digital de cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/prensariotila.com\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">01\/03\/2023<\/p>\n<p class=\"title\">Prensario TI Latin America<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/www.revistavoler.com\/single-post\/auriga-y-cms-apoyan-la-transformaci%C3%B3n-digital-de-los-cajeros-autom%C3%A1ticos-en-ecuado\">\n<td>\n<p class=\"date\">01\/03\/2023<\/p>\n<p class=\"title\">Voler<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<tr class=\"clickable-row\" data-target=\"_blank\" data-href=\"https:\/\/www.revistaeconomia.com\/auriga-y-cms-apoyan-la-transformacion-digital-de-los-cajeros-automaticos-en-ecuador\/\">\n<td>\n<p class=\"date\">28\/02\/2023<\/p>\n<p class=\"title\">Revista Econom\u00eda<\/p>\n<p class=\"sub\">Auriga y CMS apoyan la transformaci\u00f3n digital de los cajeros autom\u00e1ticos en Ecuador<\/p>\n<\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia de banca omnicanal con acceso 24\/7 a servicios personalizados, contextualizados en tiempo real, con lo que ayuda a las instituciones financieras ecuatorianas a ofrecer una mayor eficiencia operativa. Aqu\u00ed una recopilaci\u00f3n de los art\u00edculos<\/p>\n","protected":false},"author":1,"featured_media":71736,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6031],"tags":[],"class_list":["post-71735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-titulares-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Auriga y CMS en Ecuador para los proyectos de\u2026 | Auriga<\/title>\n<meta name=\"description\" content=\"A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auriga y CMS en Ecuador para los proyectos de transformaci\u00f3n de los cajeros autom\u00e1ticos | Auriga\" \/>\n<meta property=\"og:description\" content=\"A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/\" \/>\n<meta property=\"og:site_name\" content=\"Auriga\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aurigaspa\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-09T09:40:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-10T10:26:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia...\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/\"},\"author\":{\"name\":\"Roberto\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#\\\/schema\\\/person\\\/8b3ed77214b1f6af4b421d4cf1c8dced\"},\"headline\":\"Auriga y CMS en Ecuador para los proyectos de transformaci\u00f3n de los cajeros autom\u00e1ticos\",\"datePublished\":\"2023-03-09T09:40:42+00:00\",\"dateModified\":\"2023-05-10T10:26:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/\"},\"wordCount\":343,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg\",\"articleSection\":[\"Titulares de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/\",\"name\":\"Auriga y CMS en Ecuador para los proyectos de\u2026 | Auriga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg\",\"datePublished\":\"2023-03-09T09:40:42+00:00\",\"dateModified\":\"2023-05-10T10:26:18+00:00\",\"description\":\"A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg\",\"width\":850,\"height\":390,\"caption\":\"Auriga-y-CMS-Titulares-de-Prensa-ESP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/titulares-de-prensa\\\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auriga y CMS en Ecuador para los proyectos de transformaci\u00f3n de los cajeros autom\u00e1ticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/\",\"name\":\"Auriga\",\"description\":\"The banking evolution\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#organization\",\"name\":\"Auriga\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/marchio_auriga_nopayoff_web.png\",\"contentUrl\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/marchio_auriga_nopayoff_web.png\",\"width\":660,\"height\":360,\"caption\":\"Auriga\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aurigaspa\",\"https:\\\/\\\/www.instagram.com\\\/auriga_the_banking_evolution\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auriga-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aurigaspacom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#\\\/schema\\\/person\\\/8b3ed77214b1f6af4b421d4cf1c8dced\",\"name\":\"Roberto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g\",\"caption\":\"Roberto\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Auriga y CMS en Ecuador para los proyectos de\u2026 | Auriga","description":"A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/","og_locale":"es_ES","og_type":"article","og_title":"Auriga y CMS en Ecuador para los proyectos de transformaci\u00f3n de los cajeros autom\u00e1ticos | Auriga","og_description":"A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia...","og_url":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/","og_site_name":"Auriga","article_publisher":"https:\/\/www.facebook.com\/aurigaspa","article_published_time":"2023-03-09T09:40:42+00:00","article_modified_time":"2023-05-10T10:26:18+00:00","og_image":[{"width":850,"height":390,"url":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg","type":"image\/jpeg"}],"author":"Roberto","twitter_card":"summary_large_image","twitter_description":"A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia...","twitter_misc":{"Escrito por":"Roberto","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/#article","isPartOf":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/"},"author":{"name":"Roberto","@id":"https:\/\/www.aurigaspa.com\/es\/#\/schema\/person\/8b3ed77214b1f6af4b421d4cf1c8dced"},"headline":"Auriga y CMS en Ecuador para los proyectos de transformaci\u00f3n de los cajeros autom\u00e1ticos","datePublished":"2023-03-09T09:40:42+00:00","dateModified":"2023-05-10T10:26:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/"},"wordCount":343,"publisher":{"@id":"https:\/\/www.aurigaspa.com\/es\/#organization"},"image":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg","articleSection":["Titulares de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/","url":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/","name":"Auriga y CMS en Ecuador para los proyectos de\u2026 | Auriga","isPartOf":{"@id":"https:\/\/www.aurigaspa.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/#primaryimage"},"image":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg","datePublished":"2023-03-09T09:40:42+00:00","dateModified":"2023-05-10T10:26:18+00:00","description":"A trav\u00e9s de la alianza con Auriga, CMS distribuye la soluci\u00f3n WinWebServer (WWS), que proporciona a sus clientes una eficiente experiencia...","breadcrumb":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/#primaryimage","url":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg","contentUrl":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Auriga-y-CMS-Titulares-de-Prensa-ESP.jpg","width":850,"height":390,"caption":"Auriga-y-CMS-Titulares-de-Prensa-ESP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/titulares-de-prensa\/auriga-y-cms-en-ecuador-para-los-proyectos-de-transformacion-de-los-cajeros-automaticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aurigaspa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Auriga y CMS en Ecuador para los proyectos de transformaci\u00f3n de los cajeros autom\u00e1ticos"}]},{"@type":"WebSite","@id":"https:\/\/www.aurigaspa.com\/es\/#website","url":"https:\/\/www.aurigaspa.com\/es\/","name":"Auriga","description":"The banking evolution","publisher":{"@id":"https:\/\/www.aurigaspa.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aurigaspa.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aurigaspa.com\/es\/#organization","name":"Auriga","url":"https:\/\/www.aurigaspa.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aurigaspa.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/marchio_auriga_nopayoff_web.png","contentUrl":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/marchio_auriga_nopayoff_web.png","width":660,"height":360,"caption":"Auriga"},"image":{"@id":"https:\/\/www.aurigaspa.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aurigaspa","https:\/\/www.instagram.com\/auriga_the_banking_evolution\/","https:\/\/www.linkedin.com\/company\/auriga-spa","https:\/\/www.youtube.com\/user\/aurigaspacom"]},{"@type":"Person","@id":"https:\/\/www.aurigaspa.com\/es\/#\/schema\/person\/8b3ed77214b1f6af4b421d4cf1c8dced","name":"Roberto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g","caption":"Roberto"}}]}},"_links":{"self":[{"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/posts\/71735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/comments?post=71735"}],"version-history":[{"count":1,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/posts\/71735\/revisions"}],"predecessor-version":[{"id":71737,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/posts\/71735\/revisions\/71737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/media\/71736"}],"wp:attachment":[{"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/media?parent=71735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/categories?post=71735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/tags?post=71735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}