{"id":56763,"date":"2020-02-17T11:33:59","date_gmt":"2020-02-17T10:33:59","guid":{"rendered":"https:\/\/www.aurigaspa.com\/?p=56763"},"modified":"2020-02-17T11:33:59","modified_gmt":"2020-02-17T10:33:59","slug":"tecnologia-bancaria-en-2020","status":"publish","type":"post","link":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/","title":{"rendered":"\u00bfCu\u00e1l es el futuro de la tecnolog\u00eda bancaria en 2020?"},"content":{"rendered":"<p>Al igual <a href=\"https:\/\/www.aurigaspa.com\/es\/recursos\/articulos-de-opinion\/\">que el a\u00f1o pasado<\/a>, Auriga arranca el 2020 con una lista de pron\u00f3sticos sobre las tendencias que definir\u00e1n el sector bancario durante los pr\u00f3ximos 12 meses.<\/p>\n<h2>1. Las sucursales bancarias siguen siendo una necesidad<\/h2>\n<p>Las sucursales bancarias se est\u00e1n reduciendo en n\u00famero, debido a los elevados costes de gesti\u00f3n. Sin embargo, seguir\u00e1n siendo un <strong>punto de contacto vital<\/strong> para muchos clientes.<\/p>\n<p>As\u00ed pues, las sucursales que se mantengan en las calles principales experimentar\u00e1n una transformaci\u00f3n digital a trav\u00e9s de <strong>inversiones en TI<\/strong>, como, por ejemplo, la <strong>banca compartida y de \u2018marca blanca\u2019<\/strong> o la automatizaci\u00f3n completa de los procesos tradicionales.<\/p>\n<p>Esto a su vez mantendr\u00e1 la accesibilidad de los servicios financieros para los clientes, garantizando a la vez<strong> un presupuesto bajo y mejorando la experiencia del cliente<\/strong>.<\/p>\n<p>Para las generaciones m\u00e1s j\u00f3venes, el recorrido del cliente se desarrolla de forma distinta: ellos dependen mucho menos de las sucursales bancarias en comparaci\u00f3n con las generaciones anteriores, ya que est\u00e1n m\u00e1s acostumbrados a experiencias \u00fanicas y personalizadas, sobre todo en el entorno digital. Por eso esperamos que el videobanking sea cada vez m\u00e1s utilizado en el futuro de los bancos.<\/p>\n<h2>2. Demos la bienvenida a las videoconferencias<\/h2>\n<p>Las videoconferencias y la asistencia remota podr\u00e1n ayudar a los grupos demogr\u00e1ficos m\u00e1s j\u00f3venes, las personas mayores y las que viven en \u00e1reas remotas a interactuar con las sucursales de una manera completamente nueva y 24\/7, mejorando as\u00ed la relaci\u00f3n con el cliente.<\/p>\n<p>Las funcionalidades remotas se convierten en una herramienta extremamente \u00fatil para llevar a cabo operaciones bancarias que normalmente se efect\u00faan de forma presencial, ya que por ejemplo en muchas instituciones financieras europeas, los clientes deben identificarse f\u00edsicamente ante el banco para poder configurar completamente la cuenta bancaria.<\/p>\n<p>De esta manera los bancos podr\u00e1n <strong>agilizar los procesos de gesti\u00f3n<\/strong>, reducir la probabilidad de errores humanos y cerrar la brecha entre el operador y el valioso cliente, mejorando de forma notable la interacci\u00f3n general y la experiencia del usuario con la participaci\u00f3n mutua de ambas partes.<\/p>\n<p>La implementaci\u00f3n de operaciones en remoto proporciona al cliente un conjunto de posibilidades para mejorar la interacci\u00f3n con el banco en su d\u00eda a d\u00eda, como verificar los pagos y las transferencias en tiempo real, as\u00ed como recurrir a asistentes virtuales en caso de necesidad.<\/p>\n<h2>3. La IA como ventaja para rentabilizar la informaci\u00f3n de los clientes<\/h2>\n<p>La <a href=\"https:\/\/www.idc.com\/getdoc.jsp?containerId=prUS45481219\" target=\"_blank\" rel=\"noopener noreferrer\">Gu\u00eda Mundial de Gasto en Inteligencia Artificial de IDC<\/a> predice que el gasto global en inteligencia artificial podr\u00eda sumar aproximadamente 97,9 millardos de d\u00f3lares hasta 2023. Al ser una de las tecnolog\u00edas m\u00e1s disruptivas de la d\u00e9cada, los bancos tradicionales deber\u00e1n ser capaces de comprender, administrar e integrar la inteligencia artificial, entre las otras nuevas tecnolog\u00edas bancarias, en toda su infraestructura para seguir siendo competitivos.<\/p>\n<p>Esta tecnolog\u00eda permite una amplia gama de innovaciones, entre las cuales el an\u00e1lisis de datos y la customer intelligence. La inteligencia artificial puede ser utilizada para gestionar la gran cantidad de datos a disposici\u00f3n del banco, de los que se pueden sacar informaciones como tendencias, h\u00e1bitos y comportamientos que permiten comprender mejor sus necesidades y personalizar los servicios ofrecidos.<\/p>\n<p>De la misma manera, los bancos pueden analizar grandes cantitades de datos y patrones gracias a la IA y\u00a0al machine learning, para identificar actividades sospechosas, <strong>combatir el fraude en tiempo real <\/strong>y adoptar medidas inmediatas para enviar notificaciones al cliente.<\/p>\n<h2>4. El ascenso continuo de la nube<\/h2>\n<p>La adopci\u00f3n de la nube permite a los bancos mejorar su capacidad de ser resiliente y\u00a0apoyar la digitalizaci\u00f3n de nuestra sociedad de forma rentable a nivel de tiempo y costes. Los bancos se beneficiar\u00e1n de <strong>un<\/strong> <strong>impulso fundamental en sus capacidades computacionales<\/strong>, lo que har\u00e1 mucho m\u00e1s f\u00e1cil el almacenamiento y el an\u00e1lisis de lagos de datos.<\/p>\n<h2>Tendencias en continua evoluci\u00f3n<\/h2>\n<p>Estas son solo algunas de nuestras predicciones. Monitorizamos constantemente el panorama de la industria para conocer las \u00faltimas tendencias y los temas candentes, por lo que dentro de los pr\u00f3ximos meses volveremos a analizar la evoluci\u00f3n de nuestras previsiones para el 2020.<\/p>\n<p>\u00a1Seguid nuestras publicaciones para manteneros al d\u00eda!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al igual que el a\u00f1o pasado, Auriga arranca el 2020 con una lista de pron\u00f3sticos sobre las tendencias que definir\u00e1n el sector bancario durante los pr\u00f3ximos 12 meses. 1. Las sucursales bancarias siguen siendo una necesidad Las sucursales bancarias se est\u00e1n reduciendo en n\u00famero, debido a los elevados costes de gesti\u00f3n. Sin embargo, seguir\u00e1n siendo<\/p>\n","protected":false},"author":1,"featured_media":56827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6028],"tags":[],"class_list":["post-56763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-esp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfCu\u00e1l es el Futuro de la Tecnolog\u00eda Bancaria en 2020?<\/title>\n<meta name=\"description\" content=\"Auriga Arranca el Nuevo A\u00f1o con una Lista de Pron\u00f3sticos Sobre las Tendencias que Definir\u00e1n el Sector y la Tecnolog\u00eda Bancaria en 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1l es el Futuro de la Tecnolog\u00eda Bancaria en 2020?\" \/>\n<meta property=\"og:description\" content=\"Auriga Arranca el Nuevo A\u00f1o con una Lista de Pron\u00f3sticos Sobre las Tendencias que Definir\u00e1n el Sector y la Tecnolog\u00eda Bancaria en 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Auriga\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aurigaspa\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-17T10:33:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.aurigaspa.com\/wp-content\/uploads\/Tecnolog\u00eda-Bancaria-2020.jpg?fit=700%2C320&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfCu\u00e1l es el Futuro de la Tecnolog\u00eda Bancaria en 2020?\" \/>\n<meta name=\"twitter:description\" content=\"Auriga Arranca el Nuevo A\u00f1o con una Lista de Pron\u00f3sticos Sobre las Tendencias que Definir\u00e1n el Sector y la Tecnolog\u00eda Bancaria en 2020.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Tecnolog\u00eda-Bancaria-2020.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/\"},\"author\":{\"name\":\"Roberto\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#\\\/schema\\\/person\\\/8b3ed77214b1f6af4b421d4cf1c8dced\"},\"headline\":\"\u00bfCu\u00e1l es el futuro de la tecnolog\u00eda bancaria en 2020?\",\"datePublished\":\"2020-02-17T10:33:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/\"},\"wordCount\":732,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/Tecnolog\u00eda-Bancaria-2020.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/\",\"name\":\"\u00bfCu\u00e1l es el Futuro de la Tecnolog\u00eda Bancaria en 2020?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/Tecnolog\u00eda-Bancaria-2020.jpg\",\"datePublished\":\"2020-02-17T10:33:59+00:00\",\"description\":\"Auriga Arranca el Nuevo A\u00f1o con una Lista de Pron\u00f3sticos Sobre las Tendencias que Definir\u00e1n el Sector y la Tecnolog\u00eda Bancaria en 2020.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/Tecnolog\u00eda-Bancaria-2020.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/Tecnolog\u00eda-Bancaria-2020.jpg\",\"width\":700,\"height\":320,\"caption\":\"Tecnolog\u00eda Bancaria en 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/noticias-y-medios-de-comunicacion\\\/blog-esp\\\/tecnologia-bancaria-en-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1l es el futuro de la tecnolog\u00eda bancaria en 2020?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/\",\"name\":\"Auriga\",\"description\":\"The banking evolution\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#organization\",\"name\":\"Auriga\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/marchio_auriga_nopayoff_web.png\",\"contentUrl\":\"https:\\\/\\\/www.aurigaspa.com\\\/wp-content\\\/uploads\\\/marchio_auriga_nopayoff_web.png\",\"width\":660,\"height\":360,\"caption\":\"Auriga\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aurigaspa\",\"https:\\\/\\\/www.instagram.com\\\/auriga_the_banking_evolution\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auriga-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/aurigaspacom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aurigaspa.com\\\/es\\\/#\\\/schema\\\/person\\\/8b3ed77214b1f6af4b421d4cf1c8dced\",\"name\":\"Roberto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g\",\"caption\":\"Roberto\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1l es el Futuro de la Tecnolog\u00eda Bancaria en 2020?","description":"Auriga Arranca el Nuevo A\u00f1o con una Lista de Pron\u00f3sticos Sobre las Tendencias que Definir\u00e1n el Sector y la Tecnolog\u00eda Bancaria en 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1l es el Futuro de la Tecnolog\u00eda Bancaria en 2020?","og_description":"Auriga Arranca el Nuevo A\u00f1o con una Lista de Pron\u00f3sticos Sobre las Tendencias que Definir\u00e1n el Sector y la Tecnolog\u00eda Bancaria en 2020.","og_url":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/","og_site_name":"Auriga","article_publisher":"https:\/\/www.facebook.com\/aurigaspa","article_published_time":"2020-02-17T10:33:59+00:00","og_image":[{"width":700,"height":320,"url":"https:\/\/i0.wp.com\/www.aurigaspa.com\/wp-content\/uploads\/Tecnolog\u00eda-Bancaria-2020.jpg?fit=700%2C320&ssl=1","type":"image\/jpeg"}],"author":"Roberto","twitter_card":"summary_large_image","twitter_title":"\u00bfCu\u00e1l es el Futuro de la Tecnolog\u00eda Bancaria en 2020?","twitter_description":"Auriga Arranca el Nuevo A\u00f1o con una Lista de Pron\u00f3sticos Sobre las Tendencias que Definir\u00e1n el Sector y la Tecnolog\u00eda Bancaria en 2020.","twitter_image":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Tecnolog\u00eda-Bancaria-2020.jpg","twitter_misc":{"Escrito por":"Roberto","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/#article","isPartOf":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/"},"author":{"name":"Roberto","@id":"https:\/\/www.aurigaspa.com\/es\/#\/schema\/person\/8b3ed77214b1f6af4b421d4cf1c8dced"},"headline":"\u00bfCu\u00e1l es el futuro de la tecnolog\u00eda bancaria en 2020?","datePublished":"2020-02-17T10:33:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/"},"wordCount":732,"publisher":{"@id":"https:\/\/www.aurigaspa.com\/es\/#organization"},"image":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Tecnolog\u00eda-Bancaria-2020.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/","url":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/","name":"\u00bfCu\u00e1l es el Futuro de la Tecnolog\u00eda Bancaria en 2020?","isPartOf":{"@id":"https:\/\/www.aurigaspa.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Tecnolog\u00eda-Bancaria-2020.jpg","datePublished":"2020-02-17T10:33:59+00:00","description":"Auriga Arranca el Nuevo A\u00f1o con una Lista de Pron\u00f3sticos Sobre las Tendencias que Definir\u00e1n el Sector y la Tecnolog\u00eda Bancaria en 2020.","breadcrumb":{"@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/#primaryimage","url":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Tecnolog\u00eda-Bancaria-2020.jpg","contentUrl":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/Tecnolog\u00eda-Bancaria-2020.jpg","width":700,"height":320,"caption":"Tecnolog\u00eda Bancaria en 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aurigaspa.com\/es\/noticias-y-medios-de-comunicacion\/blog-esp\/tecnologia-bancaria-en-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aurigaspa.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1l es el futuro de la tecnolog\u00eda bancaria en 2020?"}]},{"@type":"WebSite","@id":"https:\/\/www.aurigaspa.com\/es\/#website","url":"https:\/\/www.aurigaspa.com\/es\/","name":"Auriga","description":"The banking evolution","publisher":{"@id":"https:\/\/www.aurigaspa.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aurigaspa.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aurigaspa.com\/es\/#organization","name":"Auriga","url":"https:\/\/www.aurigaspa.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aurigaspa.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/marchio_auriga_nopayoff_web.png","contentUrl":"https:\/\/www.aurigaspa.com\/wp-content\/uploads\/marchio_auriga_nopayoff_web.png","width":660,"height":360,"caption":"Auriga"},"image":{"@id":"https:\/\/www.aurigaspa.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aurigaspa","https:\/\/www.instagram.com\/auriga_the_banking_evolution\/","https:\/\/www.linkedin.com\/company\/auriga-spa","https:\/\/www.youtube.com\/user\/aurigaspacom"]},{"@type":"Person","@id":"https:\/\/www.aurigaspa.com\/es\/#\/schema\/person\/8b3ed77214b1f6af4b421d4cf1c8dced","name":"Roberto","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a60dc2ae898eaddf9dc429fcf2a75cb42a37382c1fa0db640d0a6f6edd0b6fec?s=96&d=mm&r=g","caption":"Roberto"}}]}},"_links":{"self":[{"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/posts\/56763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/comments?post=56763"}],"version-history":[{"count":0,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/posts\/56763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/media\/56827"}],"wp:attachment":[{"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/media?parent=56763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/categories?post=56763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aurigaspa.com\/es\/wp-json\/wp\/v2\/tags?post=56763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}